{"id":12221,"date":"2021-03-03T17:20:28","date_gmt":"2021-03-03T15:20:28","guid":{"rendered":"http:\/\/www.recinzionipvc.com\/?post_type=product&#038;p=12221"},"modified":"2022-04-13T09:39:45","modified_gmt":"2022-04-13T07:39:45","slug":"miami-palo-vergine-recinzione-pvc","status":"publish","type":"product","link":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/","title":{"rendered":"Miami Palo Vergine"},"content":{"rendered":"<em><strong>Questo tipo di palo non ha nessun tipo di fresatura.<\/strong><\/em>\r\n\r\n<em><strong>Altezze disponibili: 0,80 mt \/ 1,00 mt<\/strong><\/em>\r\n\r\n<em><strong>Da utilizzare solo ed esclusivamente con il modello Miami<\/strong><\/em>","protected":false},"excerpt":{"rendered":"<em><strong>Viene utilizzato solamente quando si necessita di un palo slegato dalla recinzione, solitamente come ancoraggio di un cancello.<\/strong><\/em>\r\n\r\n<em><strong>Questo palo \u00e8 da utilizzare solo ed esclusivamente con il modello Miami<\/strong><\/em>","protected":false},"featured_media":3433,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[660,34],"product_tag":[78,77,79,57,86,85,21,58],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palo Vergine per Recinzioni in PVC Modello Miami<\/title>\n<meta name=\"description\" content=\"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palo Vergine per Recinzioni in PVC Modello Miami\" \/>\n<meta property=\"og:description\" content=\"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/\" \/>\n<meta property=\"og:site_name\" content=\"Recinzioni PVC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-13T07:39:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"125\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/\",\"url\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/\",\"name\":\"Palo Vergine per Recinzioni in PVC Modello Miami\",\"isPartOf\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png\",\"datePublished\":\"2021-03-03T15:20:28+00:00\",\"dateModified\":\"2022-04-13T07:39:45+00:00\",\"description\":\"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere\",\"breadcrumb\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage\",\"url\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png\",\"contentUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png\",\"width\":125,\"height\":117},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recinzionipvc.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.recinzionipvc.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Miami Palo Vergine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\",\"url\":\"https:\/\/recinzionipvc.com\/it\/\",\"name\":\"Recinzioni PVC\",\"description\":\"La tua prossima recinzione, direttamente creata da te!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palo Vergine per Recinzioni in PVC Modello Miami","description":"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/","og_locale":"it_IT","og_type":"article","og_title":"Palo Vergine per Recinzioni in PVC Modello Miami","og_description":"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere","og_url":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/","og_site_name":"Recinzioni PVC","article_publisher":"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC","article_modified_time":"2022-04-13T07:39:45+00:00","og_image":[{"width":125,"height":117,"url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/","url":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/","name":"Palo Vergine per Recinzioni in PVC Modello Miami","isPartOf":{"@id":"https:\/\/recinzionipvc.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage"},"image":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage"},"thumbnailUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png","datePublished":"2021-03-03T15:20:28+00:00","dateModified":"2022-04-13T07:39:45+00:00","description":"Palo Vergine per Recinzione in PVC, modello Miami: Questo tipo di palo non ha nessun tipo di fresatura e pu\u00f2 essere lavorato a piacere","breadcrumb":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#primaryimage","url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png","contentUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/12\/palo_vergine.png","width":125,"height":117},{"@type":"BreadcrumbList","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/miami-palo-vergine-recinzione-pvc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recinzionipvc.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.recinzionipvc.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Miami Palo Vergine"}]},{"@type":"WebSite","@id":"https:\/\/recinzionipvc.com\/it\/#website","url":"https:\/\/recinzionipvc.com\/it\/","name":"Recinzioni PVC","description":"La tua prossima recinzione, direttamente creata da te!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product\/12221"}],"collection":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/comments?post=12221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media\/3433"}],"wp:attachment":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media?parent=12221"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_cat?post=12221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_tag?post=12221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}