{"id":12882,"date":"2021-07-15T15:22:05","date_gmt":"2021-07-15T13:22:05","guid":{"rendered":"http:\/\/www.recinzionipvc.com\/?post_type=product&#038;p=12882"},"modified":"2022-06-22T14:35:56","modified_gmt":"2022-06-22T12:35:56","slug":"new-lisbona-palo-terminale","status":"publish","type":"product","link":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/","title":{"rendered":"New Lisbona Palo Terminale"},"content":{"rendered":"<strong><em>Palo terminale serve per iniziare e terminare la Recinzione.<\/em><\/strong>\r\n\r\n<em><strong>Altezze disponibili: 0,95mt \/ 1,37mt\/ 1,51mt \/ 1,93mt<\/strong><\/em>\r\n\r\n<em><strong>Da utilizzare solo ed esclusivamente con il modello<span style=\"color: #000000;\"> <a style=\"color: #000000;\" href=\"https:\/\/www.recinzionipvc.com\/it\/recinzione-in-pvc-new-lisbona-con-inclinazione-a-persiana\/\">New Lisbona<\/a><\/span><\/strong><\/em>","protected":false},"excerpt":{"rendered":"<strong><i>Il palo terminale presenta le fresature su un solo lato ed \u00e8 utilizzato per iniziare o terminare la Recinzione.<\/i><\/strong>\r\n\r\n<strong><i>Questa tipologia di palo, quando si tratta di un\u2019installazione nel cemento, necessita l\u2019accoppiamento con il palo in acciaio (il quale \u00e8 a parte) per poterlo fissare su di un muretto o basamento di cemento.<\/i><\/strong>\r\n\r\n<em><strong>Questo palo \u00e8 da utilizzare solo ed esclusivamente con il modello <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.recinzionipvc.com\/it\/recinzione-in-pvc-new-lisbona-con-inclinazione-a-persiana\/\">New Lisbona<\/a>.<\/span><\/strong><\/em>","protected":false},"featured_media":6984,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[670,34],"product_tag":[78,77,79,57,667,143,86,85,21,58,666],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palo Terminale per Recinzione in PVC Modello New Lisbona<\/title>\n<meta name=\"description\" content=\"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palo Terminale per Recinzione in PVC Modello New Lisbona\" \/>\n<meta property=\"og:description\" content=\"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/\" \/>\n<meta property=\"og:site_name\" content=\"Recinzioni PVC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-22T12:35:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"125\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/\",\"url\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/\",\"name\":\"Palo Terminale per Recinzione in PVC Modello New Lisbona\",\"isPartOf\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png\",\"datePublished\":\"2021-07-15T13:22:05+00:00\",\"dateModified\":\"2022-06-22T12:35:56+00:00\",\"description\":\"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.\",\"breadcrumb\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage\",\"url\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png\",\"contentUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png\",\"width\":125,\"height\":117},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recinzionipvc.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.recinzionipvc.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"New Lisbona Palo Terminale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\",\"url\":\"https:\/\/recinzionipvc.com\/it\/\",\"name\":\"Recinzioni PVC\",\"description\":\"La tua prossima recinzione, direttamente creata da te!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palo Terminale per Recinzione in PVC Modello New Lisbona","description":"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/","og_locale":"it_IT","og_type":"article","og_title":"Palo Terminale per Recinzione in PVC Modello New Lisbona","og_description":"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.","og_url":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/","og_site_name":"Recinzioni PVC","article_publisher":"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC","article_modified_time":"2022-06-22T12:35:56+00:00","og_image":[{"width":125,"height":117,"url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/","url":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/","name":"Palo Terminale per Recinzione in PVC Modello New Lisbona","isPartOf":{"@id":"https:\/\/recinzionipvc.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage"},"image":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage"},"thumbnailUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png","datePublished":"2021-07-15T13:22:05+00:00","dateModified":"2022-06-22T12:35:56+00:00","description":"Palo Terminale, modello New Lisbona per Recinzione PVC: serve per iniziare e terminare la Recinzione.","breadcrumb":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#primaryimage","url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png","contentUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2020\/09\/palo_terminale.png","width":125,"height":117},{"@type":"BreadcrumbList","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/new-lisbona-palo-terminale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recinzionipvc.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.recinzionipvc.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"New Lisbona Palo Terminale"}]},{"@type":"WebSite","@id":"https:\/\/recinzionipvc.com\/it\/#website","url":"https:\/\/recinzionipvc.com\/it\/","name":"Recinzioni PVC","description":"La tua prossima recinzione, direttamente creata da te!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product\/12882"}],"collection":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/comments?post=12882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media\/6984"}],"wp:attachment":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media?parent=12882"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_cat?post=12882"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_tag?post=12882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}