{"id":169,"date":"2019-05-10T13:29:11","date_gmt":"2019-05-10T13:29:11","guid":{"rendered":"http:\/\/52.213.162.151\/?post_type=product&#038;p=169"},"modified":"2022-04-07T11:13:43","modified_gmt":"2022-04-07T09:13:43","slug":"parte-centrale-recinzione-pvc-madrid","status":"publish","type":"product","link":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/","title":{"rendered":"Madrid Parte Centrale"},"content":{"rendered":"<em><strong>La nostra Recinzione in PVC, modello <a href=\"https:\/\/www.recinzionipvc.com\/it\/modelli-differenti-di-recinzioni-in-pvc\/recinzione-pvc-modello-madrid-famiglia-privacy\/\">Madrid<\/a>, da un senso di libert\u00e0 in quando non possiede una traverse superiore per far &#8220;finire le traverse&#8221;, anzi, i capitelli puntano dritti verso il cielo.<\/strong><\/em>\r\n\r\n<em><strong>Il modello Madrid fa parte della famiglia <a href=\"https:\/\/www.recinzionipvc.com\/it\/famiglie-recinzioni-in-pvc\/recinzioni-pvc-famiglia-classic\/\">Classic<\/a>.<\/strong><\/em>","protected":false},"excerpt":{"rendered":"<em><strong>La nostra Recinzione in PVC, modello <a href=\"https:\/\/www.recinzionipvc.com\/it\/modelli-differenti-di-recinzioni-in-pvc\/recinzione-pvc-modello-madrid-famiglia-privacy\/\">Madrid<\/a>, \u00e8 caratterizzato da un design semplice in grado di rendere qualsiasi giardino luminoso e arioso.<\/strong><\/em>\r\n\r\n<em><strong>Il suo design richiama lo stile classico delle recinzioni caratterizzato dal gioco delle traverse posizionate &#8220;a griglia&#8221;.<\/strong><\/em>\r\n\r\n<em><strong>(La parte centrale si presenta smontata per la spedizione e non comprende i pali esterni)<\/strong><\/em>\r\n\r\n&nbsp;\r\n\r\n<strong><span style=\"color: #ff0000;\">Per visualizzare la scheda tecnica del pannello completo, cliccare <a style=\"color: #ff0000;\" href=\"https:\/\/www.recinzionipvc.com\/it\/modelli-differenti-di-recinzioni-in-pvc\/recinzione-pvc-modello-madrid-famiglia-privacy\/\">qui<\/a> e andare a fondo pagina.<\/span><\/strong>","protected":false},"featured_media":4795,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[16,105,125,31],"product_tag":[63,26,70,71,62,66,65,60,61,68,27,67,64,22,128,58,23,59,24],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parte Centrale per Recinzione in PVC Modello Madrid<\/title>\n<meta name=\"description\" content=\"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parte Centrale per Recinzione in PVC Modello Madrid\" \/>\n<meta property=\"og:description\" content=\"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Recinzioni PVC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-07T09:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/\",\"url\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/\",\"name\":\"Parte Centrale per Recinzione in PVC Modello Madrid\",\"isPartOf\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg\",\"datePublished\":\"2019-05-10T13:29:11+00:00\",\"dateModified\":\"2022-04-07T09:13:43+00:00\",\"description\":\"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni\",\"breadcrumb\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage\",\"url\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg\",\"contentUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recinzionipvc.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.recinzionipvc.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Madrid Parte Centrale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\",\"url\":\"https:\/\/recinzionipvc.com\/it\/\",\"name\":\"Recinzioni PVC\",\"description\":\"La tua prossima recinzione, direttamente creata da te!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parte Centrale per Recinzione in PVC Modello Madrid","description":"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/","og_locale":"it_IT","og_type":"article","og_title":"Parte Centrale per Recinzione in PVC Modello Madrid","og_description":"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni","og_url":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/","og_site_name":"Recinzioni PVC","article_publisher":"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC","article_modified_time":"2022-04-07T09:13:43+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/","url":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/","name":"Parte Centrale per Recinzione in PVC Modello Madrid","isPartOf":{"@id":"https:\/\/recinzionipvc.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage"},"image":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg","datePublished":"2019-05-10T13:29:11+00:00","dateModified":"2022-04-07T09:13:43+00:00","description":"La Parte Centrale della nostra Recinzione in PVC, Madrid, comprende solamente i pannelli al centro e non i due pali esterni","breadcrumb":{"@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#primaryimage","url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg","contentUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/05\/Madrid_FB3_06-Trasparente-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/recinzionipvc.com\/it\/prodotto\/parte-centrale-recinzione-pvc-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recinzionipvc.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.recinzionipvc.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Madrid Parte Centrale"}]},{"@type":"WebSite","@id":"https:\/\/recinzionipvc.com\/it\/#website","url":"https:\/\/recinzionipvc.com\/it\/","name":"Recinzioni PVC","description":"La tua prossima recinzione, direttamente creata da te!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product\/169"}],"collection":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/comments?post=169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media\/4795"}],"wp:attachment":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media?parent=169"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_cat?post=169"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_tag?post=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}