{"id":643,"date":"2019-07-11T14:13:12","date_gmt":"2019-07-11T14:13:12","guid":{"rendered":"http:\/\/52.213.162.151\/?post_type=product&#038;p=643"},"modified":"2023-01-31T16:16:26","modified_gmt":"2023-01-31T14:16:26","slug":"capitello-external-cap-recinzioni-pvc","status":"publish","type":"product","link":"https:\/\/recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/","title":{"rendered":"Capitello External Cap"},"content":{"rendered":"<em><strong>Capitello moderno, quadrato ed elegante nella sua semplicit\u00e0.<\/strong><\/em>\r\n\r\n&nbsp;","protected":false},"excerpt":{"rendered":"<em><strong>Capitello elegante e sinuoso, dona un tocco di classicit\u00e0 alla Recinzione ma senza esagerare.<\/strong><\/em>\r\n\r\n<em><strong>Ideale per chi desidera un capitello ricercato ma semplice.<\/strong><\/em>\r\n\r\n<em><strong>Adatto a qualsiasi tipo di Recinzione.<\/strong><\/em>\r\n\r\n&nbsp;\r\n\r\n&nbsp;","protected":false},"featured_media":644,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[35],"product_tag":[63,54,69,26,70,71,62,66,65,60,61,25,68,27,67,57,64,20,22,21,58,23,59,24],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capitello External Cap ideale per Recinzioni in PVC<\/title>\n<meta name=\"description\" content=\"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capitello External Cap ideale per Recinzioni in PVC\" \/>\n<meta property=\"og:description\" content=\"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/\" \/>\n<meta property=\"og:site_name\" content=\"Recinzioni PVC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T14:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png\" \/>\n\t<meta property=\"og:image:width\" content=\"125\" \/>\n\t<meta property=\"og:image:height\" content=\"125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/\",\"url\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/\",\"name\":\"Capitello External Cap ideale per Recinzioni in PVC\",\"isPartOf\":{\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png\",\"datePublished\":\"2019-07-11T14:13:12+00:00\",\"dateModified\":\"2023-01-31T14:16:26+00:00\",\"description\":\"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione\",\"breadcrumb\":{\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage\",\"url\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png\",\"contentUrl\":\"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png\",\"width\":125,\"height\":125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/recinzionipvc.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.recinzionipvc.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capitello External Cap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/recinzionipvc.com\/it\/#website\",\"url\":\"https:\/\/recinzionipvc.com\/it\/\",\"name\":\"Recinzioni PVC\",\"description\":\"La tua prossima recinzione, direttamente creata da te!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capitello External Cap ideale per Recinzioni in PVC","description":"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/","og_locale":"it_IT","og_type":"article","og_title":"Capitello External Cap ideale per Recinzioni in PVC","og_description":"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione","og_url":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/","og_site_name":"Recinzioni PVC","article_publisher":"https:\/\/www.facebook.com\/ZucchiRecinzioniPVC","article_modified_time":"2023-01-31T14:16:26+00:00","og_image":[{"width":125,"height":125,"url":"https:\/\/www.recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/","url":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/","name":"Capitello External Cap ideale per Recinzioni in PVC","isPartOf":{"@id":"https:\/\/recinzionipvc.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage"},"image":{"@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage"},"thumbnailUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png","datePublished":"2019-07-11T14:13:12+00:00","dateModified":"2023-01-31T14:16:26+00:00","description":"Capitello External Cap, ideale per Recinzioni in PVC: elegante e sinuoso dona un tocco di classicit\u00e0 alla Recinzione","breadcrumb":{"@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#primaryimage","url":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png","contentUrl":"https:\/\/recinzionipvc.com\/wp-content\/uploads\/2019\/07\/capitello_external_cap.png","width":125,"height":125},{"@type":"BreadcrumbList","@id":"https:\/\/www.recinzionipvc.com\/it\/prodotto\/capitello-external-cap-recinzioni-pvc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recinzionipvc.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.recinzionipvc.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Capitello External Cap"}]},{"@type":"WebSite","@id":"https:\/\/recinzionipvc.com\/it\/#website","url":"https:\/\/recinzionipvc.com\/it\/","name":"Recinzioni PVC","description":"La tua prossima recinzione, direttamente creata da te!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recinzionipvc.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product\/643"}],"collection":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/comments?post=643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media\/644"}],"wp:attachment":[{"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/media?parent=643"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_cat?post=643"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/recinzionipvc.com\/it\/wp-json\/wp\/v2\/product_tag?post=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}